{"id":3550,"date":"2020-07-14T16:24:20","date_gmt":"2020-07-14T14:24:20","guid":{"rendered":"http:\/\/www.sidea.org\/wp2\/?p=3550"},"modified":"2024-02-18T16:30:47","modified_gmt":"2024-02-18T15:30:47","slug":"aissa-associazione-italiana-societa-scientifiche-agrarie","status":"publish","type":"post","link":"https:\/\/www.sidea.org\/wp2\/2020\/07\/14\/aissa-associazione-italiana-societa-scientifiche-agrarie\/","title":{"rendered":"AISSA &#8211; Associazione Italiana Societ\u00e0 Scientifiche Agrarie"},"content":{"rendered":"<h1>Chi siamo<\/h1>\n<p>Nata a Firenze il 20.04.1999<br \/>\nHa sede in Firenze, Loggia degli Uffizi presso l\u2019Accademia dei Georgofili<br \/>\nDomicilio temporaneo: Facolt\u00e0 di Scienze e Tecnologie, Bolzano<\/p>\n<p>Website: <a href=\"https:\/\/www.aissa.it\/home\">www.aissa.it<\/a><\/p>\n<h4>L&#8217;Associazione, senza fini di lucro, ha lo scopo di:<\/h4>\n<ul>\n<li>favorire i rapporti tra le Societ\u00e0 Scientifiche partecipanti all&#8217;Associazione, su tematiche di interesse comune;<\/li>\n<li>favorire il coordinamento scientifico e didattico, con scambi di informazioni;<\/li>\n<li>promuovere lo svolgimento di attivit\u00e0 scientifiche e seminariali interdisciplinari in collaborazione tra i partecipanti e\/o con soggetti esterni;<\/li>\n<li>diffondere i risultati scientifici conseguiti;<\/li>\n<li>stabilire i rapporti, anche di consulenza, con le Istituzioni internazionali, nazionali e locali che sovrintendono alle attivit\u00e0 scientifiche, sperimentali formative nelle aree agraria, forestale, agroindustriale ed ambientale.<\/li>\n<\/ul>\n<h4>L&#8217;Associazione consegue tali intenti:<\/h4>\n<ul>\n<li>organizzando convegni, seminari ed incontri;<\/li>\n<li>istituendo sezioni e commissioni per lo studio di argomenti e temi specifici;<\/li>\n<li>diffondendo i risultati delle proprie attivit\u00e0;<\/li>\n<li>curando la collaborazione con Istituti ed Associazioni, anche private, che perseguono fini assimilabili;<\/li>\n<li>stabilendo rapporti, anche di consulenza, con le Istituzioni internazionali, nazionali e locali che sovrintendono alle attivit\u00e0 scientifiche, sperimentali, formative nelle aree agraria, forestale, agroindustriale ed ambientale.<\/li>\n<li>istituendo premi e borse di studio;<\/li>\n<li>svolgendo attivit\u00e0 di ricerca, sperimentali e seminariali.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Chi siamo Nata a Firenze il 20.04.1999 Ha sede in Firenze, Loggia degli Uffizi presso l\u2019Accademia dei Georgofili Domicilio temporaneo: Facolt\u00e0 di Scienze e Tecnologie, Bolzano Website: www.aissa.it L&#8217;Associazione, senza [&hellip;]<\/p>\n","protected":false},"author":11239,"featured_media":3553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[27],"tags":[],"class_list":["post-3550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documenti"],"_links":{"self":[{"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/posts\/3550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/users\/11239"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/comments?post=3550"}],"version-history":[{"count":0,"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/posts\/3550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/media\/3553"}],"wp:attachment":[{"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/media?parent=3550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/categories?post=3550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidea.org\/wp2\/wp-json\/wp\/v2\/tags?post=3550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}